{"id":10350,"date":"2021-01-01T12:49:42","date_gmt":"2021-01-01T12:49:42","guid":{"rendered":"https:\/\/startercultures.eu\/?post_type=product&#038;p=10350"},"modified":"2025-12-07T08:05:35","modified_gmt":"2025-12-07T07:05:35","slug":"online-on-demand-workshop-fermenteer-je-eigen-groente","status":"publish","type":"product","link":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/","title":{"rendered":"Online cursus &#8216;fermenteer je eigen groente&#8217;"},"content":{"rendered":"<p>Fermenteren, je hebt er vast al veel over gehoord in de afgelopen tijd. Maar wat is het nou precies? Hoe onderscheidt het zich van inmaken, wecken, inleggen in azijn en andere conserveertechnieken? Hoe doe je het veilig? Hoe weet je of het verkeerd is gegaan? Is het zo gezond als iedereen zegt?<\/p>\n<p>Al die vragen worden beantwoord tijdens deze online workshop van Meneer Wateetons, de auteur van het gezaghebbende handboek fermenteren <a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/over-rot-2-0-2019-het-geactualiseerde-handboek-fermenteren-nl\/\" target=\"_blank\" rel=\"noopener\">Over Rot<\/a> (meer dan 10.000 exemplaren verkocht). Hij leert je precies hoe je je eigen zuurkool maakt, je eigen augurkjes en je eigen kimchi. Na deze workshop kun je \u00e9lke groente zelf fermenteren omdat je de techniek snapt!<\/p>\n<h3>WAT GA JE LEREN?<\/h3>\n<p>\u2705 Tijdens deze cursus komt zowel de theorie als de praktijk aan bod.<br \/>\n\u2705 Alles handig stapsgewijs uitgelegd en gedemonstreerd.<br \/>\n\u2705 Welke materialen heb je nodig? Verrassend weinig!<br \/>\n\u2705 Met de basistechniek in de vingers kun je onbeperkt vari\u00ebren en je eigen recepten verzinnen.<br \/>\n\u2705 Met veel tips en tricks van de auteur van <a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/over-rot-2-0-2019-het-geactualiseerde-handboek-fermenteren-nl\/\" target=\"_blank\" rel=\"noopener\">Over Rot<\/a>.<br \/>\n\u2705 Veel aandacht voor veiligheid.<br \/>\n\u2705 Aandacht voor de gezondheidsaspecten van gefermenteerde groente<br \/>\n\u2705 Online, dus gewoon vanuit je luie stoel.<br \/>\n\u2705 Blijvende toegang<\/p>\n<h3>Videopreview online cursus &#8216;fermenteer je eigen groente&#8217;<\/h3>\n<div style=\"padding: 56.25% 0 0 0; position: relative;\"><iframe style=\"position: absolute; top: 0; left: 0; width: 100%; height: 100%;\" title=\"groente fermenteren 1 wat ga je leren\" src=\"https:\/\/player.vimeo.com\/video\/541600544?h=1c35121fc5&amp;title=0&amp;byline=0&amp;portrait=0&amp;badge=0&amp;autopause=0&amp;player_id=0&amp;app_id=58479\" frameborder=\"0\"><\/iframe><\/div>\n<p><script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script><\/p>\n<h3>Voordelen van de online cursus &#8216;fermenteer je eigen groente&#8217;<\/h3>\n<p>\u2714\ufe0f13 korte duidelijke lessen.<br \/>\n\u2714\ufe0fKijken op je eigen moment en overal ter wereld.<br \/>\n\u2714\ufe0fTerugspoelen en herhalen zo vaak als je wilt.<br \/>\n\u2714\ufe0fInclusief powerpoint<\/p>\n<h3>Relevant boek<span style=\"font-size: 16px;\">n\u00a0<\/span><\/h3>\n<ul>\n<li><a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/over-rot-2-0-2019-het-geactualiseerde-handboek-fermenteren-nl\/\" target=\"_blank\" rel=\"noopener\">Over Rot<\/a>.<\/li>\n<\/ul>\n<h3>Workshopleider<\/h3>\n<p>De cursus wordt gegeven door <a href=\"https:\/\/wateetons.com\/over-wateetons\/\" target=\"_blank\" rel=\"noopener noreferrer\">Meneer Wateetons<\/a> auteur van negen gezaghebbende kookboeken (<a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/handboek-voor-de-vinex-jager-nl\/\" target=\"_blank\" rel=\"noopener\">Handboek voor de Vinex-jager<\/a> (2010), Over Worst (2011), <a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/over-rook-2014-nl\/\" target=\"_blank\" rel=\"noopener\">Over Rook<\/a> (2014), <a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/over-rot-2-0-2019-het-geactualiseerde-handboek-fermenteren-nl\/\" target=\"_blank\" rel=\"noopener\">Over Rot<\/a> (2015), <a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/over-drank-2016-nl\/\" target=\"_blank\" rel=\"noopener\">Over Drank<\/a> (2016), de <a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/worstbijbel-2018-nl\/\" target=\"_blank\" rel=\"noopener\">Worstbijbel<\/a>\u00a0 (2018), <a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/over-charcuterie-2019-nl\/\" target=\"_blank\" rel=\"noopener\">Over Charcuterie<\/a> (2019), <a href=\"https:\/\/startercultures.eu\/nl\/product\/boeken\/over-inpakken-2020-nl\/\" target=\"_blank\" rel=\"noopener\">Over Inpakken<\/a> (2020) en <a href=\"https:\/\/startercultures.eu\/nl\/product\/uncategorized\/over-frituren\/\" target=\"_blank\" rel=\"noopener\">Over Frituren<\/a> (2022), culinair blogger sinds 2006 (<a href=\"https:\/\/www.wateetons.com\/\">www.wateetons.com<\/a>) en columnist (oa. columnist voor Elle Eten, Nrc Next en Winelife). Hij geeft al bijna vijftien jaar humoristische, leerzame, smakelijke en gezellige culinaire workshops en masterclasses waar je daadwerkelijk wat van opsteekt. Zowel voor hobbyisten, als voor professionals als koks en koks in opleiding, als voor bedrijven. Zijn workshops worden op <a href=\"https:\/\/www.facebook.com\/pg\/wateetons\/reviews\/\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook beoordeeld met 4.9 sterren<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fermenteren, je hebt er vast al veel over gehoord in de afgelopen tijd. Maar wat is het nou precies? Hoe onderscheidt het zich van inmaken, wecken, inleggen in azijn en andere conserveertechnieken? Hoe doe je het veilig? Hoe weet je of het verkeerd is gegaan? Is het zo gezond als iedereen zegt? Al die vragen worden beantwoord tijdens deze online workshop van Meneer Wateetons.<\/p>\n","protected":false},"featured_media":75374,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"product_brand":[],"product_cat":[451,32,413,415],"product_tag":[],"class_list":{"0":"post-10350","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-online-workshops-fermenteren-nl","7":"product_cat-groente-nl","8":"product_cat-online-workshops-nl","9":"product_cat-workshops-vegetables-nl","11":"first","12":"instock","13":"downloadable","14":"virtual","15":"taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Online cursus &#039;fermenteer je eigen groente&#039; - starterculturen.nl<\/title>\n<meta name=\"description\" content=\"Wat is fermenteren? Is het gezond? Is het lekker? Is het veilig? Al deze vragen worden beantwoord tijdens deze online workshop van Meneer Wateetons?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online cursus &#039;fermenteer je eigen groente&#039; - starterculturen.nl\" \/>\n<meta property=\"og:description\" content=\"Wat is fermenteren? Is het gezond? Is het lekker? Is het veilig? Al deze vragen worden beantwoord tijdens deze online workshop van Meneer Wateetons?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/\" \/>\n<meta property=\"og:site_name\" content=\"Startercultures.eu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startercultureseu\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-07T07:05:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startercultures.eu\/wp-content\/uploads\/2021\/01\/GROENTE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,99\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Op voorraad\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/\",\"url\":\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/\",\"name\":\"Online cursus 'fermenteer je eigen groente' - starterculturen.nl\",\"isPartOf\":{\"@id\":\"https:\/\/startercultures.eu\/nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/startercultures.eu\/wp-content\/uploads\/2021\/01\/GROENTE.png\",\"datePublished\":\"2021-01-01T12:49:42+00:00\",\"dateModified\":\"2025-12-07T07:05:35+00:00\",\"description\":\"Wat is fermenteren? Is het gezond? Is het lekker? Is het veilig? Al deze vragen worden beantwoord tijdens deze online workshop van Meneer Wateetons?\",\"breadcrumb\":{\"@id\":\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#primaryimage\",\"url\":\"https:\/\/startercultures.eu\/wp-content\/uploads\/2021\/01\/GROENTE.png\",\"contentUrl\":\"https:\/\/startercultures.eu\/wp-content\/uploads\/2021\/01\/GROENTE.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/startercultures.eu\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\/\/startercultures.eu\/nl\/winkel\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Online cursus &#8216;fermenteer je eigen groente&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/startercultures.eu\/nl\/#website\",\"url\":\"https:\/\/startercultures.eu\/nl\/\",\"name\":\"Startercultures.eu\",\"description\":\"Startercultures.eu\",\"publisher\":{\"@id\":\"https:\/\/startercultures.eu\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/startercultures.eu\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/startercultures.eu\/nl\/#organization\",\"name\":\"Startercultures.eu\",\"url\":\"https:\/\/startercultures.eu\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/startercultures.eu\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/startercultures.eu\/wp-content\/uploads\/2020\/08\/startercultures-eu-nl-logo-rond-rgb.png\",\"contentUrl\":\"https:\/\/startercultures.eu\/wp-content\/uploads\/2020\/08\/startercultures-eu-nl-logo-rond-rgb.png\",\"width\":320,\"height\":320,\"caption\":\"Startercultures.eu\"},\"image\":{\"@id\":\"https:\/\/startercultures.eu\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/startercultureseu\",\"https:\/\/www.instagram.com\/startercultures.eu\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\/\/startercultures.eu\/return-policy\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.99\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"364\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online cursus 'fermenteer je eigen groente' - starterculturen.nl","description":"Wat is fermenteren? Is het gezond? Is het lekker? Is het veilig? Al deze vragen worden beantwoord tijdens deze online workshop van Meneer Wateetons?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/","og_locale":"nl_NL","og_type":"article","og_title":"Online cursus 'fermenteer je eigen groente' - starterculturen.nl","og_description":"Wat is fermenteren? Is het gezond? Is het lekker? Is het veilig? Al deze vragen worden beantwoord tijdens deze online workshop van Meneer Wateetons?","og_url":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/","og_site_name":"Startercultures.eu","article_publisher":"https:\/\/www.facebook.com\/startercultureseu","article_modified_time":"2025-12-07T07:05:35+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/startercultures.eu\/wp-content\/uploads\/2021\/01\/GROENTE.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,99","Availability":"Op voorraad"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/","url":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/","name":"Online cursus 'fermenteer je eigen groente' - starterculturen.nl","isPartOf":{"@id":"https:\/\/startercultures.eu\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#primaryimage"},"image":{"@id":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#primaryimage"},"thumbnailUrl":"https:\/\/startercultures.eu\/wp-content\/uploads\/2021\/01\/GROENTE.png","datePublished":"2021-01-01T12:49:42+00:00","dateModified":"2025-12-07T07:05:35+00:00","description":"Wat is fermenteren? Is het gezond? Is het lekker? Is het veilig? Al deze vragen worden beantwoord tijdens deze online workshop van Meneer Wateetons?","breadcrumb":{"@id":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#primaryimage","url":"https:\/\/startercultures.eu\/wp-content\/uploads\/2021\/01\/GROENTE.png","contentUrl":"https:\/\/startercultures.eu\/wp-content\/uploads\/2021\/01\/GROENTE.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/startercultures.eu\/nl\/product\/online-workshops-nl\/online-on-demand-workshop-fermenteer-je-eigen-groente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/startercultures.eu\/nl\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/startercultures.eu\/nl\/winkel\/"},{"@type":"ListItem","position":3,"name":"Online cursus &#8216;fermenteer je eigen groente&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/startercultures.eu\/nl\/#website","url":"https:\/\/startercultures.eu\/nl\/","name":"Startercultures.eu","description":"Startercultures.eu","publisher":{"@id":"https:\/\/startercultures.eu\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/startercultures.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/startercultures.eu\/nl\/#organization","name":"Startercultures.eu","url":"https:\/\/startercultures.eu\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/startercultures.eu\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/startercultures.eu\/wp-content\/uploads\/2020\/08\/startercultures-eu-nl-logo-rond-rgb.png","contentUrl":"https:\/\/startercultures.eu\/wp-content\/uploads\/2020\/08\/startercultures-eu-nl-logo-rond-rgb.png","width":320,"height":320,"caption":"Startercultures.eu"},"image":{"@id":"https:\/\/startercultures.eu\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/startercultureseu","https:\/\/www.instagram.com\/startercultures.eu\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/startercultures.eu\/return-policy\/"}}]},"product_price_amount":"14.99","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"364","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/product\/10350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/comments?post=10350"}],"version-history":[{"count":8,"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/product\/10350\/revisions"}],"predecessor-version":[{"id":76853,"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/product\/10350\/revisions\/76853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/media\/75374"}],"wp:attachment":[{"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/media?parent=10350"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/product_brand?post=10350"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/product_cat?post=10350"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/startercultures.eu\/nl\/wp-json\/wp\/v2\/product_tag?post=10350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}